{"id":1243,"date":"2024-01-29T10:28:43","date_gmt":"2024-01-29T10:28:43","guid":{"rendered":"https:\/\/ai-grid.org\/?page_id=1243"},"modified":"2026-03-09T13:00:31","modified_gmt":"2026-03-09T13:00:31","slug":"for-mentors","status":"publish","type":"page","link":"https:\/\/ai-grid.org\/en\/for-mentors\/","title":{"rendered":"For mentors"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"1243\" class=\"elementor elementor-1243\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c4e0207 e-ecs-flex e-flex e-con-boxed e-con e-parent\" data-id=\"c4e0207\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[],&quot;ecs_container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b954b6b e-ecs-flex e-flex e-con-boxed e-con e-parent\" data-id=\"b954b6b\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[],&quot;ecs_container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-99a123c elementor-widget elementor-widget-heading\" data-id=\"99a123c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Mitmachen als Mentor:in<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-aefda71 elementor-widget elementor-widget-text-editor\" data-id=\"aefda71\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Als AI Grid Mentor:in f\u00f6rdern Sie den KI-Nachwuchs und st\u00e4rken den KI-Standort Deutschland. Sie begleiten talentierte Masterstudierende und Doktorand:innen, bleiben nah an aktuellen Entwicklungen der KI-Forschung und vernetzen sich mit f\u00fchrenden Expert:innen aus Wissenschaft und Wirtschaft.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bbf7891 elementor-mobile-align-justify elementor-widget-mobile__width-inherit elementor-align-right elementor-widget elementor-widget-button\" data-id=\"bbf7891\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-bob\" href=\"https:\/\/community.ai-grid.org\/Public\/RegisterAsMentor.aspx\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Jetzt bewerben<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e93eb1a elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e93eb1a\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[],&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-710d226\" data-id=\"710d226\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-72bd8ac elementor-widget elementor-widget-icon-box\" data-id=\"72bd8ac\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h4 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tKI-Nachwuchs f\u00f6rdern.\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h4>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tSie profitieren von neuesten Erkenntnissen in KI-Spitzenthemen.<br>\n\n<br>Mindestanforderungen f\u00fcr Mentor:innen:<br> - Bedeutende Fachkenntnisse in einem Bereich mit Bezug zur K\u00fcnstlichen Intelligenz (KI).<br>- Mindestens drei Jahre relevante Berufserfahrung in einem verwandten T\u00e4tigkeitsfeld.<br>\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-30f1a10 elementor-widget elementor-widget-icon-box\" data-id=\"30f1a10\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h2 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tKI Standort Deutschland st\u00e4rken.\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h2>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tDas AI Grid f\u00f6rdert aktiv die Forschung in Deutschland. Es bringt junge talentierte K\u00f6pfe und erfahrene Experten zusammen, um den KI-Nachwuchs von morgen zu sichern.\n\nSie werden \u00fcber die neusten Entwicklungen in der KI direkt und kontinuierlich informiert.\n\nSie sind eine Schl\u00fcsselfigur in einem attraktiven Umfeld in Wissenschaft und Wirtschaft, das hochspezialisierten jungen Talenten eine Perspektive gibt.\n\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cada4da elementor-widget elementor-widget-icon-box\" data-id=\"cada4da\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h2 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tForschung vorantreiben.\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h2>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tAusgew\u00e4hlte Masterstudierende und Doktorand:innen teilen ihre Erkenntnisse mit Ihnen und bringen Sie stets auf den neusten Stand in ihrem Feld. Als Mentor:in unterst\u00fctzen und ermutigen Sie Ihre Mentees, indem Sie einen wissenschaftlichen Beitrag zum Forschungsthema leisten. Sie haben die M\u00f6glichkeit, gemeinsam mit ihren Mentees zu ver\u00f6ffentlichen. Die Ver\u00f6ffentlichungen flie\u00dfen an prominenter Stelle in die Kommunikation des AI Grid ein.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6929558 elementor-widget elementor-widget-icon-box\" data-id=\"6929558\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h2 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tImpulse geben.\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h2>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tSie sind Impulsgeber:in f\u00fcr den talentierten KI-Nachwuchs und f\u00f6rdern gezielt wissenschaftliche und wirtschaftliche Karrieren.\n\nSie geben wertvolle und pragmatische Tipps zu wegweisender wissenschaftlicher Literatur, Publikationsm\u00f6glichkeiten und Veranstaltungen.\n\nSie initiieren gemeinsame Ver\u00f6ffentlichungen mit Ihren Mentees.\n\nSie profitieren von Kooperationsprojekten und Kontakten in die Wirtschaft, die im AI Grid entstehen.\n\nSie machen diese neue, vom BMBF finanzierte Initiative, bekannt.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b99aa5a elementor-widget elementor-widget-icon-box\" data-id=\"b99aa5a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h2 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tInspirierende Kontakte.\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h2>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tSie sind in direktem Kontakt mit den talentiertesten Nachwuchsforscher:innen Europas.\n\nSie sind Teil eines hochkar\u00e4tigen Expertennetzwerks aus nationalen und internationalen Professoren und KI-Expert:innen.\n\nSie erhalten Kontakte zu relevanten Partnern in hochwertigen Forschungszentren, Universit\u00e4ten in ganz Europa.\n\nSie werden jedes Jahr zu unserem mehrt\u00e4gigen Seminar eingeladen, das die gesamte AI-Grid-Community an einem gro\u00dfartigen Ort zusammenbringt.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1965a3d elementor-section-content-top elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1965a3d\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9039ceb\" data-id=\"9039ceb\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-c69e3e9 elementor-section-content-bottom animated-slow elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"c69e3e9\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[],&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-dc233f1\" data-id=\"dc233f1\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6968e0e elementor-widget elementor-widget-heading\" data-id=\"6968e0e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Wie werde ich Mentor:in?\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8df1f4e elementor-widget elementor-widget-text-editor\" data-id=\"8df1f4e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Die meisten Mentor:innen kommen auf Empfehlung zu uns. Wenn es Sie interessiert, Mentor:in im AI Grid zu sein, kontaktieren Sie uns gern.<\/p><p><strong>Engagieren Sie sich f\u00fcr die n\u00e4chste KI-Generation \u201eMade in Europe\u201c.<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-92b5024 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"92b5024\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-xl\" href=\"https:\/\/community.ai-grid.org\/Public\/RegisterAsMentor.aspx\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Zum Formular \u2192<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0938683 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0938683\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a83a11a\" data-id=\"a83a11a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-84b9084 elementor-widget elementor-widget-heading\" data-id=\"84b9084\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Senior Mentor:innen<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4b2edcc elementor-widget elementor-widget-jet-listing-grid\" data-id=\"4b2edcc\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;columns_mobile&quot;:&quot;1&quot;,&quot;columns&quot;:3}\" data-widget_type=\"jet-listing-grid.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"jet-listing-grid jet-listing\"><div class=\"jet-listing-grid__items grid-col-desk-3 grid-col-tablet-3 grid-col-mobile-1 jet-listing-grid--2015\" data-queried-id=\"1243|WP_Post\" data-nav=\"{&quot;enabled&quot;:false,&quot;type&quot;:null,&quot;more_el&quot;:null,&quot;query&quot;:[],&quot;widget_settings&quot;:{&quot;lisitng_id&quot;:2015,&quot;posts_num&quot;:6,&quot;columns&quot;:3,&quot;columns_tablet&quot;:3,&quot;columns_mobile&quot;:1,&quot;column_min_width&quot;:240,&quot;column_min_width_tablet&quot;:240,&quot;column_min_width_mobile&quot;:240,&quot;inline_columns_css&quot;:false,&quot;is_archive_template&quot;:&quot;&quot;,&quot;post_status&quot;:[&quot;publish&quot;],&quot;use_random_posts_num&quot;:&quot;&quot;,&quot;max_posts_num&quot;:9,&quot;not_found_message&quot;:&quot;No data was found&quot;,&quot;is_masonry&quot;:false,&quot;equal_columns_height&quot;:&quot;&quot;,&quot;use_load_more&quot;:&quot;&quot;,&quot;load_more_id&quot;:&quot;&quot;,&quot;load_more_type&quot;:&quot;click&quot;,&quot;load_more_offset&quot;:null,&quot;use_custom_post_types&quot;:&quot;&quot;,&quot;custom_post_types&quot;:[],&quot;hide_widget_if&quot;:&quot;&quot;,&quot;carousel_enabled&quot;:&quot;&quot;,&quot;slides_to_scroll&quot;:&quot;1&quot;,&quot;arrows&quot;:&quot;true&quot;,&quot;arrow_icon&quot;:&quot;fa fa-angle-left&quot;,&quot;dots&quot;:&quot;&quot;,&quot;autoplay&quot;:&quot;true&quot;,&quot;pause_on_hover&quot;:&quot;true&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;true&quot;,&quot;center_mode&quot;:&quot;&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500,&quot;inject_alternative_items&quot;:&quot;&quot;,&quot;injection_items&quot;:[],&quot;scroll_slider_enabled&quot;:&quot;&quot;,&quot;scroll_slider_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;],&quot;custom_query&quot;:false,&quot;custom_query_id&quot;:&quot;&quot;,&quot;_element_id&quot;:&quot;&quot;,&quot;collapse_first_last_gap&quot;:false,&quot;list_tag_selection&quot;:&quot;&quot;,&quot;list_items_wrapper_tag&quot;:&quot;div&quot;,&quot;list_item_tag&quot;:&quot;div&quot;,&quot;empty_items_wrapper_tag&quot;:&quot;div&quot;}}\" data-page=\"1\" data-pages=\"1\" data-listing-source=\"posts\" data-listing-id=\"2015\" data-query-id=\"\"><div class=\"jet-listing-grid__item jet-listing-dynamic-post-1389\" data-post-id=\"1389\"  ><div class=\"jet-engine-listing-overlay-wrap\" data-url=\"https:\/\/www.uni-augsburg.de\/en\/fakultaet\/fai\/informatik\/prof\/hcm\/team\/andre\/\" data-target=\"_blank\">\t\t<div data-elementor-type=\"jet-listing-items\" data-elementor-id=\"2015\" class=\"elementor elementor-2015\" data-elementor-post-type=\"jet-engine\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fca78a4 elementor-section-height-min-height elementor-section-items-stretch elementor-section-boxed elementor-section-height-default\" data-id=\"fca78a4\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ebb2671\" data-id=\"ebb2671\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9c517f3 elementor-widget elementor-widget-theme-post-featured-image elementor-widget-image\" data-id=\"9c517f3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-featured-image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/ai-grid.org\/en\/mentor\/prof-dr-elisabeth-andre\/\">\n\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/ai-grid.org\/wp-content\/uploads\/2024\/02\/10_Elisabeth-Andre-ab01f122-1920w-300x300.jpg\" class=\"attachment-medium size-medium wp-image-1561\" alt=\"\" srcset=\"https:\/\/ai-grid.org\/wp-content\/uploads\/2024\/02\/10_Elisabeth-Andre-ab01f122-1920w-300x300.jpg 300w, https:\/\/ai-grid.org\/wp-content\/uploads\/2024\/02\/10_Elisabeth-Andre-ab01f122-1920w-1024x1024.jpg 1024w, https:\/\/ai-grid.org\/wp-content\/uploads\/2024\/02\/10_Elisabeth-Andre-ab01f122-1920w-150x150.jpg 150w, https:\/\/ai-grid.org\/wp-content\/uploads\/2024\/02\/10_Elisabeth-Andre-ab01f122-1920w-768x768.jpg 768w, https:\/\/ai-grid.org\/wp-content\/uploads\/2024\/02\/10_Elisabeth-Andre-ab01f122-1920w.jpg 1275w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-977196b elementor-widget__width-auto elementor-widget elementor-widget-heading\" data-id=\"977196b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Prof. Dr. Elisabeth Andr\u00e9<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0c47db6 elementor-widget__width-auto elementor-widget elementor-widget-heading\" data-id=\"0c47db6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Inhaberin des Lehrstuhls f\u00fcr Multimodale Mensch-Technik Interaktion am Institut f\u00fcr Informatik - Universit\u00e4t Augsburg<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-df2626f elementor-absolute elementor-widget elementor-widget-heading\" data-id=\"df2626f\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/www.uni-augsburg.de\/en\/fakultaet\/fai\/informatik\/prof\/hcm\/team\/andre\/\" target=\"_blank\">Mehr Erfahren<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<a href=\"https:\/\/www.uni-augsburg.de\/en\/fakultaet\/fai\/informatik\/prof\/hcm\/team\/andre\/\" class=\"jet-engine-listing-overlay-link\" target=\"_blank\"><\/a><\/div><\/div><div class=\"jet-listing-grid__item jet-listing-dynamic-post-1391\" data-post-id=\"1391\"  ><div class=\"jet-engine-listing-overlay-wrap\" data-url=\"http:\/\/hans.uszkoreit.net\/\" data-target=\"_blank\">\t\t<div data-elementor-type=\"jet-listing-items\" data-elementor-id=\"2015\" class=\"elementor elementor-2015\" data-elementor-post-type=\"jet-engine\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fca78a4 elementor-section-height-min-height elementor-section-items-stretch elementor-section-boxed elementor-section-height-default\" data-id=\"fca78a4\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ebb2671\" data-id=\"ebb2671\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9c517f3 elementor-widget elementor-widget-theme-post-featured-image elementor-widget-image\" data-id=\"9c517f3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-featured-image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/ai-grid.org\/en\/mentor\/prof-dr-hans-uszkoreit\/\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/ai-grid.org\/wp-content\/uploads\/2024\/02\/03_Hans-Uszkoreit-43c1b794-1920w-300x300.jpeg\" class=\"attachment-medium size-medium wp-image-1554\" alt=\"\" srcset=\"https:\/\/ai-grid.org\/wp-content\/uploads\/2024\/02\/03_Hans-Uszkoreit-43c1b794-1920w-300x300.jpeg 300w, https:\/\/ai-grid.org\/wp-content\/uploads\/2024\/02\/03_Hans-Uszkoreit-43c1b794-1920w-1024x1024.jpeg 1024w, https:\/\/ai-grid.org\/wp-content\/uploads\/2024\/02\/03_Hans-Uszkoreit-43c1b794-1920w-150x150.jpeg 150w, https:\/\/ai-grid.org\/wp-content\/uploads\/2024\/02\/03_Hans-Uszkoreit-43c1b794-1920w-768x768.jpeg 768w, https:\/\/ai-grid.org\/wp-content\/uploads\/2024\/02\/03_Hans-Uszkoreit-43c1b794-1920w.jpeg 1490w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-977196b elementor-widget__width-auto elementor-widget elementor-widget-heading\" data-id=\"977196b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Prof. Dr. Hans Uszkoreit<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0c47db6 elementor-widget__width-auto elementor-widget elementor-widget-heading\" data-id=\"0c47db6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Scientific Director im DFKI<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-df2626f elementor-absolute elementor-widget elementor-widget-heading\" data-id=\"df2626f\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"http:\/\/hans.uszkoreit.net\/\" target=\"_blank\">Mehr Erfahren<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<a href=\"http:\/\/hans.uszkoreit.net\/\" class=\"jet-engine-listing-overlay-link\" target=\"_blank\"><\/a><\/div><\/div><div class=\"jet-listing-grid__item jet-listing-dynamic-post-2038\" data-post-id=\"2038\"  ><div class=\"jet-engine-listing-overlay-wrap\" data-url=\"https:\/\/www.benerichson.com\/\" data-target=\"_blank\">\t\t<div data-elementor-type=\"jet-listing-items\" data-elementor-id=\"2015\" class=\"elementor elementor-2015\" data-elementor-post-type=\"jet-engine\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fca78a4 elementor-section-height-min-height elementor-section-items-stretch elementor-section-boxed elementor-section-height-default\" data-id=\"fca78a4\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ebb2671\" data-id=\"ebb2671\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9c517f3 elementor-widget elementor-widget-theme-post-featured-image elementor-widget-image\" data-id=\"9c517f3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-featured-image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/ai-grid.org\/en\/mentor\/dr-n-benjamin-erichson\/\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/ai-grid.org\/wp-content\/uploads\/2024\/02\/Ben_profile_2022-ff1ce24b-1920w-300x300.webp\" class=\"attachment-medium size-medium wp-image-2041\" alt=\"\" srcset=\"https:\/\/ai-grid.org\/wp-content\/uploads\/2024\/02\/Ben_profile_2022-ff1ce24b-1920w-300x300.webp 300w, https:\/\/ai-grid.org\/wp-content\/uploads\/2024\/02\/Ben_profile_2022-ff1ce24b-1920w-1024x1024.webp 1024w, https:\/\/ai-grid.org\/wp-content\/uploads\/2024\/02\/Ben_profile_2022-ff1ce24b-1920w-150x150.webp 150w, https:\/\/ai-grid.org\/wp-content\/uploads\/2024\/02\/Ben_profile_2022-ff1ce24b-1920w-768x768.webp 768w, https:\/\/ai-grid.org\/wp-content\/uploads\/2024\/02\/Ben_profile_2022-ff1ce24b-1920w.webp 1385w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-977196b elementor-widget__width-auto elementor-widget elementor-widget-heading\" data-id=\"977196b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Dr. N. Benjamin Erichson<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0c47db6 elementor-widget__width-auto elementor-widget elementor-widget-heading\" data-id=\"0c47db6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Senior Research Scientist - International Computer Science Institute (Universit\u00e4t von Kalifornien in Berkeley, USA)<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-df2626f elementor-absolute elementor-widget elementor-widget-heading\" data-id=\"df2626f\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/www.benerichson.com\/\" target=\"_blank\">Mehr Erfahren<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<a href=\"https:\/\/www.benerichson.com\/\" class=\"jet-engine-listing-overlay-link\" target=\"_blank\"><\/a><\/div><\/div><div class=\"jet-listing-grid__item jet-listing-dynamic-post-1393\" data-post-id=\"1393\"  ><div class=\"jet-engine-listing-overlay-wrap\" data-url=\"https:\/\/research.nii.ac.jp\/~iechizen\/official\/members_echizen-e.html\" data-target=\"_blank\">\t\t<div data-elementor-type=\"jet-listing-items\" data-elementor-id=\"2015\" class=\"elementor elementor-2015\" data-elementor-post-type=\"jet-engine\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fca78a4 elementor-section-height-min-height elementor-section-items-stretch elementor-section-boxed elementor-section-height-default\" data-id=\"fca78a4\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ebb2671\" data-id=\"ebb2671\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9c517f3 elementor-widget elementor-widget-theme-post-featured-image elementor-widget-image\" data-id=\"9c517f3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-featured-image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/ai-grid.org\/en\/mentor\/prof-dr-isao-echizen\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/ai-grid.org\/wp-content\/uploads\/2024\/02\/22_fig_IsaoEchizen-1920w-300x300.jpg\" class=\"attachment-medium size-medium wp-image-1573\" alt=\"\" srcset=\"https:\/\/ai-grid.org\/wp-content\/uploads\/2024\/02\/22_fig_IsaoEchizen-1920w-300x300.jpg 300w, https:\/\/ai-grid.org\/wp-content\/uploads\/2024\/02\/22_fig_IsaoEchizen-1920w-1024x1024.jpg 1024w, https:\/\/ai-grid.org\/wp-content\/uploads\/2024\/02\/22_fig_IsaoEchizen-1920w-150x150.jpg 150w, https:\/\/ai-grid.org\/wp-content\/uploads\/2024\/02\/22_fig_IsaoEchizen-1920w-768x768.jpg 768w, https:\/\/ai-grid.org\/wp-content\/uploads\/2024\/02\/22_fig_IsaoEchizen-1920w-1536x1536.jpg 1536w, https:\/\/ai-grid.org\/wp-content\/uploads\/2024\/02\/22_fig_IsaoEchizen-1920w.jpg 1920w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-977196b elementor-widget__width-auto elementor-widget elementor-widget-heading\" data-id=\"977196b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Prof. Dr. Isao Echizen<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0c47db6 elementor-widget__width-auto elementor-widget elementor-widget-heading\" data-id=\"0c47db6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Professor National Institute of Informatics (Tokio, Japan)<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-df2626f elementor-absolute elementor-widget elementor-widget-heading\" data-id=\"df2626f\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/research.nii.ac.jp\/~iechizen\/official\/members_echizen-e.html\" target=\"_blank\">Mehr Erfahren<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<a href=\"https:\/\/research.nii.ac.jp\/~iechizen\/official\/members_echizen-e.html\" class=\"jet-engine-listing-overlay-link\" target=\"_blank\"><\/a><\/div><\/div><div class=\"jet-listing-grid__item jet-listing-dynamic-post-1395\" data-post-id=\"1395\"  ><div class=\"jet-engine-listing-overlay-wrap\" data-url=\"https:\/\/www.icsi.berkeley.edu\/icsi\/people\/jwu\" data-target=\"_blank\">\t\t<div data-elementor-type=\"jet-listing-items\" data-elementor-id=\"2015\" class=\"elementor elementor-2015\" data-elementor-post-type=\"jet-engine\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fca78a4 elementor-section-height-min-height elementor-section-items-stretch elementor-section-boxed elementor-section-height-default\" data-id=\"fca78a4\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ebb2671\" data-id=\"ebb2671\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9c517f3 elementor-widget elementor-widget-theme-post-featured-image elementor-widget-image\" data-id=\"9c517f3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-featured-image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/ai-grid.org\/en\/mentor\/john-wu\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"240\" height=\"300\" src=\"https:\/\/ai-grid.org\/wp-content\/uploads\/2024\/02\/04_JohnWu1702c-1920w-240x300.jpg\" class=\"attachment-medium size-medium wp-image-1555\" alt=\"\" srcset=\"https:\/\/ai-grid.org\/wp-content\/uploads\/2024\/02\/04_JohnWu1702c-1920w-240x300.jpg 240w, https:\/\/ai-grid.org\/wp-content\/uploads\/2024\/02\/04_JohnWu1702c-1920w-768x960.jpg 768w, https:\/\/ai-grid.org\/wp-content\/uploads\/2024\/02\/04_JohnWu1702c-1920w.jpg 800w\" sizes=\"(max-width: 240px) 100vw, 240px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-977196b elementor-widget__width-auto elementor-widget elementor-widget-heading\" data-id=\"977196b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Prof. Dr. John Wu<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0c47db6 elementor-widget__width-auto elementor-widget elementor-widget-heading\" data-id=\"0c47db6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Senior Computer Scientist und Forschungsleiter  (International Computer Science Institute, Berkeley, USA)<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-df2626f elementor-absolute elementor-widget elementor-widget-heading\" data-id=\"df2626f\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/www.icsi.berkeley.edu\/icsi\/people\/jwu\" target=\"_blank\">Mehr Erfahren<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<a href=\"https:\/\/www.icsi.berkeley.edu\/icsi\/people\/jwu\" class=\"jet-engine-listing-overlay-link\" target=\"_blank\"><\/a><\/div><\/div><div class=\"jet-listing-grid__item jet-listing-dynamic-post-2051\" data-post-id=\"2051\"  ><div class=\"jet-engine-listing-overlay-wrap\" data-url=\"https:\/\/www.rolfdrechsler.de\/\" data-target=\"_blank\">\t\t<div data-elementor-type=\"jet-listing-items\" data-elementor-id=\"2015\" class=\"elementor elementor-2015\" data-elementor-post-type=\"jet-engine\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fca78a4 elementor-section-height-min-height elementor-section-items-stretch elementor-section-boxed elementor-section-height-default\" data-id=\"fca78a4\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ebb2671\" data-id=\"ebb2671\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9c517f3 elementor-widget elementor-widget-theme-post-featured-image elementor-widget-image\" data-id=\"9c517f3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-featured-image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/ai-grid.org\/en\/mentor\/prof-dr-rolf-drechsler\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/ai-grid.org\/wp-content\/uploads\/2024\/02\/Drechsler_Portrait_hoch_300-5f1f1f30-1920w-300x300.webp\" class=\"attachment-medium size-medium wp-image-2053\" alt=\"\" srcset=\"https:\/\/ai-grid.org\/wp-content\/uploads\/2024\/02\/Drechsler_Portrait_hoch_300-5f1f1f30-1920w-300x300.webp 300w, https:\/\/ai-grid.org\/wp-content\/uploads\/2024\/02\/Drechsler_Portrait_hoch_300-5f1f1f30-1920w-1024x1024.webp 1024w, https:\/\/ai-grid.org\/wp-content\/uploads\/2024\/02\/Drechsler_Portrait_hoch_300-5f1f1f30-1920w-150x150.webp 150w, https:\/\/ai-grid.org\/wp-content\/uploads\/2024\/02\/Drechsler_Portrait_hoch_300-5f1f1f30-1920w-768x768.webp 768w, https:\/\/ai-grid.org\/wp-content\/uploads\/2024\/02\/Drechsler_Portrait_hoch_300-5f1f1f30-1920w-1536x1536.webp 1536w, https:\/\/ai-grid.org\/wp-content\/uploads\/2024\/02\/Drechsler_Portrait_hoch_300-5f1f1f30-1920w.webp 1920w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-977196b elementor-widget__width-auto elementor-widget elementor-widget-heading\" data-id=\"977196b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Prof. Dr. Rolf Drechsler<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0c47db6 elementor-widget__width-auto elementor-widget elementor-widget-heading\" data-id=\"0c47db6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"> Direktor am DFKI, Leiter des Forschungsbereichs Cyber-Physical Systems (CPS), Universit\u00e4t Bremen\/DFKI<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-df2626f elementor-absolute elementor-widget elementor-widget-heading\" data-id=\"df2626f\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/www.rolfdrechsler.de\/\" target=\"_blank\">Mehr Erfahren<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<a href=\"https:\/\/www.rolfdrechsler.de\/\" class=\"jet-engine-listing-overlay-link\" target=\"_blank\"><\/a><\/div><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1309cdb elementor-widget elementor-widget-heading\" data-id=\"1309cdb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Mentor:innen<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c435f13 elementor-widget elementor-widget-jet-listing-grid\" data-id=\"c435f13\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;columns_mobile&quot;:&quot;1&quot;,&quot;columns&quot;:3}\" data-widget_type=\"jet-listing-grid.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"jet-listing-grid jet-listing\"><div class=\"jet-listing-grid__items grid-col-desk-3 grid-col-tablet-3 grid-col-mobile-1 jet-listing-grid--2015\" data-queried-id=\"1243|WP_Post\" data-nav=\"{&quot;enabled&quot;:false,&quot;type&quot;:null,&quot;more_el&quot;:null,&quot;query&quot;:[],&quot;widget_settings&quot;:{&quot;lisitng_id&quot;:2015,&quot;posts_num&quot;:12,&quot;columns&quot;:3,&quot;columns_tablet&quot;:3,&quot;columns_mobile&quot;:1,&quot;column_min_width&quot;:240,&quot;column_min_width_tablet&quot;:240,&quot;column_min_width_mobile&quot;:240,&quot;inline_columns_css&quot;:false,&quot;is_archive_template&quot;:&quot;&quot;,&quot;post_status&quot;:[&quot;publish&quot;],&quot;use_random_posts_num&quot;:&quot;&quot;,&quot;max_posts_num&quot;:9,&quot;not_found_message&quot;:&quot;No data was found&quot;,&quot;is_masonry&quot;:false,&quot;equal_columns_height&quot;:&quot;&quot;,&quot;use_load_more&quot;:&quot;&quot;,&quot;load_more_id&quot;:&quot;&quot;,&quot;load_more_type&quot;:&quot;click&quot;,&quot;load_more_offset&quot;:null,&quot;use_custom_post_types&quot;:&quot;&quot;,&quot;custom_post_types&quot;:[],&quot;hide_widget_if&quot;:&quot;&quot;,&quot;carousel_enabled&quot;:&quot;&quot;,&quot;slides_to_scroll&quot;:&quot;1&quot;,&quot;arrows&quot;:&quot;true&quot;,&quot;arrow_icon&quot;:&quot;fa fa-angle-left&quot;,&quot;dots&quot;:&quot;&quot;,&quot;autoplay&quot;:&quot;true&quot;,&quot;pause_on_hover&quot;:&quot;true&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;true&quot;,&quot;center_mode&quot;:&quot;&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500,&quot;inject_alternative_items&quot;:&quot;&quot;,&quot;injection_items&quot;:[],&quot;scroll_slider_enabled&quot;:&quot;&quot;,&quot;scroll_slider_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;],&quot;custom_query&quot;:false,&quot;custom_query_id&quot;:&quot;&quot;,&quot;_element_id&quot;:&quot;&quot;,&quot;collapse_first_last_gap&quot;:false,&quot;list_tag_selection&quot;:&quot;&quot;,&quot;list_items_wrapper_tag&quot;:&quot;div&quot;,&quot;list_item_tag&quot;:&quot;div&quot;,&quot;empty_items_wrapper_tag&quot;:&quot;div&quot;}}\" data-page=\"1\" data-pages=\"7\" data-listing-source=\"posts\" data-listing-id=\"2015\" data-query-id=\"\"><div class=\"jet-listing-grid__item jet-listing-dynamic-post-8012\" data-post-id=\"8012\"  ><div class=\"jet-engine-listing-overlay-wrap\" data-url=\"https:\/\/scholar.google.com\/citations?user=R2ntI8IAAAAJ&amp;hl=en\" data-target=\"_blank\">\t\t<div data-elementor-type=\"jet-listing-items\" data-elementor-id=\"2015\" class=\"elementor elementor-2015\" data-elementor-post-type=\"jet-engine\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fca78a4 elementor-section-height-min-height elementor-section-items-stretch elementor-section-boxed elementor-section-height-default\" data-id=\"fca78a4\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ebb2671\" data-id=\"ebb2671\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9c517f3 elementor-widget elementor-widget-theme-post-featured-image elementor-widget-image\" data-id=\"9c517f3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-featured-image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/ai-grid.org\/en\/mentor\/kevin-jablonka\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"250\" height=\"250\" src=\"https:\/\/ai-grid.org\/wp-content\/uploads\/2025\/12\/Kevin_Jablonka.png\" class=\"attachment-medium size-medium wp-image-8013\" alt=\"\" srcset=\"https:\/\/ai-grid.org\/wp-content\/uploads\/2025\/12\/Kevin_Jablonka.png 250w, https:\/\/ai-grid.org\/wp-content\/uploads\/2025\/12\/Kevin_Jablonka-150x150.png 150w, https:\/\/ai-grid.org\/wp-content\/uploads\/2025\/12\/Kevin_Jablonka-12x12.png 12w\" sizes=\"(max-width: 250px) 100vw, 250px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-977196b elementor-widget__width-auto elementor-widget elementor-widget-heading\" data-id=\"977196b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Dr. Kevin Jablonka<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0c47db6 elementor-widget__width-auto elementor-widget elementor-widget-heading\" data-id=\"0c47db6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Research Group Leader, Helmholtz Center Berlin \/ FSU Jena<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-df2626f elementor-absolute elementor-widget elementor-widget-heading\" data-id=\"df2626f\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/scholar.google.com\/citations?user=R2ntI8IAAAAJ&#038;hl=en\" target=\"_blank\">Mehr Erfahren<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<a href=\"https:\/\/scholar.google.com\/citations?user=R2ntI8IAAAAJ&amp;hl=en\" class=\"jet-engine-listing-overlay-link\" target=\"_blank\"><\/a><\/div><\/div><div class=\"jet-listing-grid__item jet-listing-dynamic-post-8009\" data-post-id=\"8009\"  ><div class=\"jet-engine-listing-overlay-wrap\" data-url=\"https:\/\/www.linkedin.com\/in\/laura-crompton\/\" data-target=\"_blank\">\t\t<div data-elementor-type=\"jet-listing-items\" data-elementor-id=\"2015\" class=\"elementor elementor-2015\" data-elementor-post-type=\"jet-engine\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fca78a4 elementor-section-height-min-height elementor-section-items-stretch elementor-section-boxed elementor-section-height-default\" data-id=\"fca78a4\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ebb2671\" data-id=\"ebb2671\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9c517f3 elementor-widget elementor-widget-theme-post-featured-image elementor-widget-image\" data-id=\"9c517f3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-featured-image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/ai-grid.org\/en\/mentor\/laura-crompton\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"250\" height=\"250\" src=\"https:\/\/ai-grid.org\/wp-content\/uploads\/2025\/12\/laura-crompton.png\" class=\"attachment-medium size-medium wp-image-8011\" alt=\"\" srcset=\"https:\/\/ai-grid.org\/wp-content\/uploads\/2025\/12\/laura-crompton.png 250w, https:\/\/ai-grid.org\/wp-content\/uploads\/2025\/12\/laura-crompton-150x150.png 150w, https:\/\/ai-grid.org\/wp-content\/uploads\/2025\/12\/laura-crompton-12x12.png 12w\" sizes=\"(max-width: 250px) 100vw, 250px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-977196b elementor-widget__width-auto elementor-widget elementor-widget-heading\" data-id=\"977196b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Prof. Dr. Laura Crompton<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0c47db6 elementor-widget__width-auto elementor-widget elementor-widget-heading\" data-id=\"0c47db6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Professorin KI Ethik, Technische Hochschule Ingolstadt<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-df2626f elementor-absolute elementor-widget elementor-widget-heading\" data-id=\"df2626f\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/www.linkedin.com\/in\/laura-crompton\/\" target=\"_blank\">Mehr Erfahren<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<a href=\"https:\/\/www.linkedin.com\/in\/laura-crompton\/\" class=\"jet-engine-listing-overlay-link\" target=\"_blank\"><\/a><\/div><\/div><div class=\"jet-listing-grid__item jet-listing-dynamic-post-8006\" data-post-id=\"8006\"  ><div class=\"jet-engine-listing-overlay-wrap\" data-url=\"https:\/\/scholar.google.com\/citations?user=ttVRli8AAAAJ&amp;hl=en\" data-target=\"_blank\">\t\t<div data-elementor-type=\"jet-listing-items\" data-elementor-id=\"2015\" class=\"elementor elementor-2015\" data-elementor-post-type=\"jet-engine\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fca78a4 elementor-section-height-min-height elementor-section-items-stretch elementor-section-boxed elementor-section-height-default\" data-id=\"fca78a4\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ebb2671\" data-id=\"ebb2671\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9c517f3 elementor-widget elementor-widget-theme-post-featured-image elementor-widget-image\" data-id=\"9c517f3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-featured-image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/ai-grid.org\/en\/mentor\/gerard-chollet\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"86\" height=\"128\" src=\"https:\/\/ai-grid.org\/wp-content\/uploads\/2025\/12\/Gerard_Chollet-.jpeg\" class=\"attachment-medium size-medium wp-image-8008\" alt=\"\" srcset=\"https:\/\/ai-grid.org\/wp-content\/uploads\/2025\/12\/Gerard_Chollet-.jpeg 86w, https:\/\/ai-grid.org\/wp-content\/uploads\/2025\/12\/Gerard_Chollet--8x12.jpeg 8w\" sizes=\"(max-width: 86px) 100vw, 86px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-977196b elementor-widget__width-auto elementor-widget elementor-widget-heading\" data-id=\"977196b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Dr. G\u00e9rard Chollet<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0c47db6 elementor-widget__width-auto elementor-widget elementor-widget-heading\" data-id=\"0c47db6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">DR-Emeritus, CNRS<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-df2626f elementor-absolute elementor-widget elementor-widget-heading\" data-id=\"df2626f\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/scholar.google.com\/citations?user=ttVRli8AAAAJ&#038;hl=en\" target=\"_blank\">Mehr Erfahren<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<a href=\"https:\/\/scholar.google.com\/citations?user=ttVRli8AAAAJ&amp;hl=en\" class=\"jet-engine-listing-overlay-link\" target=\"_blank\"><\/a><\/div><\/div><div class=\"jet-listing-grid__item jet-listing-dynamic-post-8002\" data-post-id=\"8002\"  ><div class=\"jet-engine-listing-overlay-wrap\" data-url=\"https:\/\/scholar.google.com\/citations?user=xqcTCeUAAAAJ&amp;hl=de\" data-target=\"_blank\">\t\t<div data-elementor-type=\"jet-listing-items\" data-elementor-id=\"2015\" class=\"elementor elementor-2015\" data-elementor-post-type=\"jet-engine\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fca78a4 elementor-section-height-min-height elementor-section-items-stretch elementor-section-boxed elementor-section-height-default\" data-id=\"fca78a4\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ebb2671\" data-id=\"ebb2671\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9c517f3 elementor-widget elementor-widget-theme-post-featured-image elementor-widget-image\" data-id=\"9c517f3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-featured-image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/ai-grid.org\/en\/mentor\/zully-ritter\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"250\" height=\"250\" src=\"https:\/\/ai-grid.org\/wp-content\/uploads\/2025\/12\/Zully_Ritter.png\" class=\"attachment-medium size-medium wp-image-8003\" alt=\"\" srcset=\"https:\/\/ai-grid.org\/wp-content\/uploads\/2025\/12\/Zully_Ritter.png 250w, https:\/\/ai-grid.org\/wp-content\/uploads\/2025\/12\/Zully_Ritter-150x150.png 150w, https:\/\/ai-grid.org\/wp-content\/uploads\/2025\/12\/Zully_Ritter-12x12.png 12w\" sizes=\"(max-width: 250px) 100vw, 250px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-977196b elementor-widget__width-auto elementor-widget elementor-widget-heading\" data-id=\"977196b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Dr. rer. medic. Zully Ritter<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0c47db6 elementor-widget__width-auto elementor-widget elementor-widget-heading\" data-id=\"0c47db6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Senior Post-Doc, Universit\u00e4tsmedizin G\u00f6ttingen<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-df2626f elementor-absolute elementor-widget elementor-widget-heading\" data-id=\"df2626f\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/scholar.google.com\/citations?user=xqcTCeUAAAAJ&#038;hl=de\" target=\"_blank\">Mehr Erfahren<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<a href=\"https:\/\/scholar.google.com\/citations?user=xqcTCeUAAAAJ&amp;hl=de\" class=\"jet-engine-listing-overlay-link\" target=\"_blank\"><\/a><\/div><\/div><div class=\"jet-listing-grid__item jet-listing-dynamic-post-7744\" data-post-id=\"7744\"  ><div class=\"jet-engine-listing-overlay-wrap\" data-url=\"https:\/\/scholar.google.com\/citations?user=nRW4gQQAAAAJ&amp;hl=en\" data-target=\"_blank\">\t\t<div data-elementor-type=\"jet-listing-items\" data-elementor-id=\"2015\" class=\"elementor elementor-2015\" data-elementor-post-type=\"jet-engine\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fca78a4 elementor-section-height-min-height elementor-section-items-stretch elementor-section-boxed elementor-section-height-default\" data-id=\"fca78a4\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ebb2671\" data-id=\"ebb2671\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9c517f3 elementor-widget elementor-widget-theme-post-featured-image elementor-widget-image\" data-id=\"9c517f3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-featured-image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/ai-grid.org\/en\/mentor\/patrick-ebel\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"250\" height=\"250\" src=\"https:\/\/ai-grid.org\/wp-content\/uploads\/2025\/10\/Patrick-Ebel.png\" class=\"attachment-medium size-medium wp-image-7745\" alt=\"\" srcset=\"https:\/\/ai-grid.org\/wp-content\/uploads\/2025\/10\/Patrick-Ebel.png 250w, https:\/\/ai-grid.org\/wp-content\/uploads\/2025\/10\/Patrick-Ebel-150x150.png 150w, https:\/\/ai-grid.org\/wp-content\/uploads\/2025\/10\/Patrick-Ebel-12x12.png 12w\" sizes=\"(max-width: 250px) 100vw, 250px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-977196b elementor-widget__width-auto elementor-widget elementor-widget-heading\" data-id=\"977196b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Dr. Patrick Ebel<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0c47db6 elementor-widget__width-auto elementor-widget elementor-widget-heading\" data-id=\"0c47db6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Junior Research Group Leader, ScaDS.AI, Leipzig University<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-df2626f elementor-absolute elementor-widget elementor-widget-heading\" data-id=\"df2626f\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/scholar.google.com\/citations?user=nRW4gQQAAAAJ&#038;hl=en\" target=\"_blank\">Mehr Erfahren<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<a href=\"https:\/\/scholar.google.com\/citations?user=nRW4gQQAAAAJ&amp;hl=en\" class=\"jet-engine-listing-overlay-link\" target=\"_blank\"><\/a><\/div><\/div><div class=\"jet-listing-grid__item jet-listing-dynamic-post-7741\" data-post-id=\"7741\"  ><div class=\"jet-engine-listing-overlay-wrap\" data-url=\"https:\/\/scholar.google.com\/citations?user=SJabMHsAAAAJ\" data-target=\"_blank\">\t\t<div data-elementor-type=\"jet-listing-items\" data-elementor-id=\"2015\" class=\"elementor elementor-2015\" data-elementor-post-type=\"jet-engine\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fca78a4 elementor-section-height-min-height elementor-section-items-stretch elementor-section-boxed elementor-section-height-default\" data-id=\"fca78a4\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ebb2671\" data-id=\"ebb2671\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9c517f3 elementor-widget elementor-widget-theme-post-featured-image elementor-widget-image\" data-id=\"9c517f3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-featured-image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/ai-grid.org\/en\/mentor\/clemens-schefels\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"250\" height=\"250\" src=\"https:\/\/ai-grid.org\/wp-content\/uploads\/2025\/10\/Clemens-Schefels.png\" class=\"attachment-medium size-medium wp-image-7742\" alt=\"\" srcset=\"https:\/\/ai-grid.org\/wp-content\/uploads\/2025\/10\/Clemens-Schefels.png 250w, https:\/\/ai-grid.org\/wp-content\/uploads\/2025\/10\/Clemens-Schefels-150x150.png 150w, https:\/\/ai-grid.org\/wp-content\/uploads\/2025\/10\/Clemens-Schefels-12x12.png 12w\" sizes=\"(max-width: 250px) 100vw, 250px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-977196b elementor-widget__width-auto elementor-widget elementor-widget-heading\" data-id=\"977196b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Dr. phil. nat. Clemens Schefels<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0c47db6 elementor-widget__width-auto elementor-widget elementor-widget-heading\" data-id=\"0c47db6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Forschungssoftwareingenieur und Datenwissenschaftler, Institut f\u00fcr Raumfahrtbetrieb und Astronautentraining<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-df2626f elementor-absolute elementor-widget elementor-widget-heading\" data-id=\"df2626f\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/scholar.google.com\/citations?user=SJabMHsAAAAJ\" target=\"_blank\">Mehr Erfahren<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<a href=\"https:\/\/scholar.google.com\/citations?user=SJabMHsAAAAJ\" class=\"jet-engine-listing-overlay-link\" target=\"_blank\"><\/a><\/div><\/div><div class=\"jet-listing-grid__item jet-listing-dynamic-post-7738\" data-post-id=\"7738\"  ><div class=\"jet-engine-listing-overlay-wrap\" data-url=\"https:\/\/www.linkedin.com\/in\/duongtrungnghia\/\" data-target=\"_blank\">\t\t<div data-elementor-type=\"jet-listing-items\" data-elementor-id=\"2015\" class=\"elementor elementor-2015\" data-elementor-post-type=\"jet-engine\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fca78a4 elementor-section-height-min-height elementor-section-items-stretch elementor-section-boxed elementor-section-height-default\" data-id=\"fca78a4\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ebb2671\" data-id=\"ebb2671\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9c517f3 elementor-widget elementor-widget-theme-post-featured-image elementor-widget-image\" data-id=\"9c517f3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-featured-image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/ai-grid.org\/en\/mentor\/nghia-duong-trung\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"250\" height=\"250\" src=\"https:\/\/ai-grid.org\/wp-content\/uploads\/2025\/10\/Nghia-Duong-Trung.png\" class=\"attachment-medium size-medium wp-image-7739\" alt=\"\" srcset=\"https:\/\/ai-grid.org\/wp-content\/uploads\/2025\/10\/Nghia-Duong-Trung.png 250w, https:\/\/ai-grid.org\/wp-content\/uploads\/2025\/10\/Nghia-Duong-Trung-150x150.png 150w, https:\/\/ai-grid.org\/wp-content\/uploads\/2025\/10\/Nghia-Duong-Trung-12x12.png 12w\" sizes=\"(max-width: 250px) 100vw, 250px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-977196b elementor-widget__width-auto elementor-widget elementor-widget-heading\" data-id=\"977196b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Dr. Nghia Duong-Trung<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0c47db6 elementor-widget__width-auto elementor-widget elementor-widget-heading\" data-id=\"0c47db6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Senior Researcher, DFKI<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-df2626f elementor-absolute elementor-widget elementor-widget-heading\" data-id=\"df2626f\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/www.linkedin.com\/in\/duongtrungnghia\/\" target=\"_blank\">Mehr Erfahren<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<a href=\"https:\/\/www.linkedin.com\/in\/duongtrungnghia\/\" class=\"jet-engine-listing-overlay-link\" target=\"_blank\"><\/a><\/div><\/div><div class=\"jet-listing-grid__item jet-listing-dynamic-post-7735\" data-post-id=\"7735\"  ><div class=\"jet-engine-listing-overlay-wrap\" data-url=\"https:\/\/www.linkedin.com\/in\/arne-ewald\/\" data-target=\"_blank\">\t\t<div data-elementor-type=\"jet-listing-items\" data-elementor-id=\"2015\" class=\"elementor elementor-2015\" data-elementor-post-type=\"jet-engine\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fca78a4 elementor-section-height-min-height elementor-section-items-stretch elementor-section-boxed elementor-section-height-default\" data-id=\"fca78a4\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ebb2671\" data-id=\"ebb2671\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9c517f3 elementor-widget elementor-widget-theme-post-featured-image elementor-widget-image\" data-id=\"9c517f3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-featured-image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/ai-grid.org\/en\/mentor\/arne-ewald\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"250\" height=\"250\" src=\"https:\/\/ai-grid.org\/wp-content\/uploads\/2025\/10\/Arne-Ewald.png\" class=\"attachment-medium size-medium wp-image-7736\" alt=\"\" srcset=\"https:\/\/ai-grid.org\/wp-content\/uploads\/2025\/10\/Arne-Ewald.png 250w, https:\/\/ai-grid.org\/wp-content\/uploads\/2025\/10\/Arne-Ewald-150x150.png 150w, https:\/\/ai-grid.org\/wp-content\/uploads\/2025\/10\/Arne-Ewald-12x12.png 12w\" sizes=\"(max-width: 250px) 100vw, 250px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-977196b elementor-widget__width-auto elementor-widget elementor-widget-heading\" data-id=\"977196b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Prof. Dr. Arne Ewald<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0c47db6 elementor-widget__width-auto elementor-widget elementor-widget-heading\" data-id=\"0c47db6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Professor for Data Science, NORDAKADEMIE University of Applied Sciences<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-df2626f elementor-absolute elementor-widget elementor-widget-heading\" data-id=\"df2626f\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/www.linkedin.com\/in\/arne-ewald\/\" target=\"_blank\">Mehr Erfahren<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<a href=\"https:\/\/www.linkedin.com\/in\/arne-ewald\/\" class=\"jet-engine-listing-overlay-link\" target=\"_blank\"><\/a><\/div><\/div><div class=\"jet-listing-grid__item jet-listing-dynamic-post-7732\" data-post-id=\"7732\"  ><div class=\"jet-engine-listing-overlay-wrap\" data-url=\"https:\/\/www.linkedin.com\/in\/gesina-schwalbe-2301b495\/\" data-target=\"_blank\">\t\t<div data-elementor-type=\"jet-listing-items\" data-elementor-id=\"2015\" class=\"elementor elementor-2015\" data-elementor-post-type=\"jet-engine\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fca78a4 elementor-section-height-min-height elementor-section-items-stretch elementor-section-boxed elementor-section-height-default\" data-id=\"fca78a4\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ebb2671\" data-id=\"ebb2671\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9c517f3 elementor-widget elementor-widget-theme-post-featured-image elementor-widget-image\" data-id=\"9c517f3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-featured-image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/ai-grid.org\/en\/mentor\/gesina-schwalbe\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"250\" height=\"250\" src=\"https:\/\/ai-grid.org\/wp-content\/uploads\/2025\/10\/Gesina-Schwalbe.png\" class=\"attachment-medium size-medium wp-image-7733\" alt=\"\" srcset=\"https:\/\/ai-grid.org\/wp-content\/uploads\/2025\/10\/Gesina-Schwalbe.png 250w, https:\/\/ai-grid.org\/wp-content\/uploads\/2025\/10\/Gesina-Schwalbe-150x150.png 150w, https:\/\/ai-grid.org\/wp-content\/uploads\/2025\/10\/Gesina-Schwalbe-12x12.png 12w\" sizes=\"(max-width: 250px) 100vw, 250px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-977196b elementor-widget__width-auto elementor-widget elementor-widget-heading\" data-id=\"977196b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Dr. Gesina Schwalbe<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0c47db6 elementor-widget__width-auto elementor-widget elementor-widget-heading\" data-id=\"0c47db6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Lead of Junior Research Group on Correctable Hybrid Artificial Intelligence, University of L\u00fcbeck<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-df2626f elementor-absolute elementor-widget elementor-widget-heading\" data-id=\"df2626f\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/www.linkedin.com\/in\/gesina-schwalbe-2301b495\/\" target=\"_blank\">Mehr Erfahren<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<a href=\"https:\/\/www.linkedin.com\/in\/gesina-schwalbe-2301b495\/\" class=\"jet-engine-listing-overlay-link\" target=\"_blank\"><\/a><\/div><\/div><div class=\"jet-listing-grid__item jet-listing-dynamic-post-7729\" data-post-id=\"7729\"  ><div class=\"jet-engine-listing-overlay-wrap\" data-url=\"https:\/\/scholar.google.com\/citations?user=VKVsvw4AAAAJ&amp;hl=de\" data-target=\"_blank\">\t\t<div data-elementor-type=\"jet-listing-items\" data-elementor-id=\"2015\" class=\"elementor elementor-2015\" data-elementor-post-type=\"jet-engine\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fca78a4 elementor-section-height-min-height elementor-section-items-stretch elementor-section-boxed elementor-section-height-default\" data-id=\"fca78a4\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ebb2671\" data-id=\"ebb2671\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9c517f3 elementor-widget elementor-widget-theme-post-featured-image elementor-widget-image\" data-id=\"9c517f3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-featured-image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/ai-grid.org\/en\/mentor\/matthias-demant\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"250\" height=\"250\" src=\"https:\/\/ai-grid.org\/wp-content\/uploads\/2025\/10\/Matthias-Demant.png\" class=\"attachment-medium size-medium wp-image-7730\" alt=\"\" srcset=\"https:\/\/ai-grid.org\/wp-content\/uploads\/2025\/10\/Matthias-Demant.png 250w, https:\/\/ai-grid.org\/wp-content\/uploads\/2025\/10\/Matthias-Demant-150x150.png 150w, https:\/\/ai-grid.org\/wp-content\/uploads\/2025\/10\/Matthias-Demant-12x12.png 12w\" sizes=\"(max-width: 250px) 100vw, 250px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-977196b elementor-widget__width-auto elementor-widget elementor-widget-heading\" data-id=\"977196b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Dr.Ing. \/ Dipl.Inf. Matthias Demant<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0c47db6 elementor-widget__width-auto elementor-widget elementor-widget-heading\" data-id=\"0c47db6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Head of Group \"Image Processing and Machine Learning\", Fraunhofer ISE<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-df2626f elementor-absolute elementor-widget elementor-widget-heading\" data-id=\"df2626f\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/scholar.google.com\/citations?user=VKVsvw4AAAAJ&#038;hl=de\" target=\"_blank\">Mehr Erfahren<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<a href=\"https:\/\/scholar.google.com\/citations?user=VKVsvw4AAAAJ&amp;hl=de\" class=\"jet-engine-listing-overlay-link\" target=\"_blank\"><\/a><\/div><\/div><div class=\"jet-listing-grid__item jet-listing-dynamic-post-7726\" data-post-id=\"7726\"  ><div class=\"jet-engine-listing-overlay-wrap\" data-url=\"https:\/\/uni-tuebingen.de\/de\/143985\" data-target=\"_blank\">\t\t<div data-elementor-type=\"jet-listing-items\" data-elementor-id=\"2015\" class=\"elementor elementor-2015\" data-elementor-post-type=\"jet-engine\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fca78a4 elementor-section-height-min-height elementor-section-items-stretch elementor-section-boxed elementor-section-height-default\" data-id=\"fca78a4\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ebb2671\" data-id=\"ebb2671\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9c517f3 elementor-widget elementor-widget-theme-post-featured-image elementor-widget-image\" data-id=\"9c517f3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-featured-image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/ai-grid.org\/en\/mentor\/reinhard-kahle\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"250\" height=\"250\" src=\"https:\/\/ai-grid.org\/wp-content\/uploads\/2025\/10\/Reinhard-Kahle.png\" class=\"attachment-medium size-medium wp-image-7727\" alt=\"\" srcset=\"https:\/\/ai-grid.org\/wp-content\/uploads\/2025\/10\/Reinhard-Kahle.png 250w, https:\/\/ai-grid.org\/wp-content\/uploads\/2025\/10\/Reinhard-Kahle-150x150.png 150w, https:\/\/ai-grid.org\/wp-content\/uploads\/2025\/10\/Reinhard-Kahle-12x12.png 12w\" sizes=\"(max-width: 250px) 100vw, 250px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-977196b elementor-widget__width-auto elementor-widget elementor-widget-heading\" data-id=\"977196b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Prof. Dr. Reinhard Kahle<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0c47db6 elementor-widget__width-auto elementor-widget elementor-widget-heading\" data-id=\"0c47db6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Head of Carl Friedrich von Weizs\u00e4cker Center, Universit\u00e4t T\u00fcbingen<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-df2626f elementor-absolute elementor-widget elementor-widget-heading\" data-id=\"df2626f\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/uni-tuebingen.de\/de\/143985\" target=\"_blank\">Mehr Erfahren<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<a href=\"https:\/\/uni-tuebingen.de\/de\/143985\" class=\"jet-engine-listing-overlay-link\" target=\"_blank\"><\/a><\/div><\/div><div class=\"jet-listing-grid__item jet-listing-dynamic-post-7722\" data-post-id=\"7722\"  ><div class=\"jet-engine-listing-overlay-wrap\" data-url=\"https:\/\/www.linkedin.com\/in\/gerrit-gro%C3%9Fmann\/\" data-target=\"_blank\">\t\t<div data-elementor-type=\"jet-listing-items\" data-elementor-id=\"2015\" class=\"elementor elementor-2015\" data-elementor-post-type=\"jet-engine\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fca78a4 elementor-section-height-min-height elementor-section-items-stretch elementor-section-boxed elementor-section-height-default\" data-id=\"fca78a4\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ebb2671\" data-id=\"ebb2671\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9c517f3 elementor-widget elementor-widget-theme-post-featured-image elementor-widget-image\" data-id=\"9c517f3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-featured-image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/ai-grid.org\/en\/mentor\/gerrit-grossmann\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"250\" height=\"250\" src=\"https:\/\/ai-grid.org\/wp-content\/uploads\/2025\/10\/Gerrit-Grossmann.png\" class=\"attachment-medium size-medium wp-image-7724\" alt=\"\" srcset=\"https:\/\/ai-grid.org\/wp-content\/uploads\/2025\/10\/Gerrit-Grossmann.png 250w, https:\/\/ai-grid.org\/wp-content\/uploads\/2025\/10\/Gerrit-Grossmann-150x150.png 150w, https:\/\/ai-grid.org\/wp-content\/uploads\/2025\/10\/Gerrit-Grossmann-12x12.png 12w\" sizes=\"(max-width: 250px) 100vw, 250px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-977196b elementor-widget__width-auto elementor-widget elementor-widget-heading\" data-id=\"977196b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Dr. Gerrit Grossmann<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0c47db6 elementor-widget__width-auto elementor-widget elementor-widget-heading\" data-id=\"0c47db6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Post-doctoral Researcher, DFKI<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-df2626f elementor-absolute elementor-widget elementor-widget-heading\" data-id=\"df2626f\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/www.linkedin.com\/in\/gerrit-gro%C3%9Fmann\/\" target=\"_blank\">Mehr Erfahren<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<a href=\"https:\/\/www.linkedin.com\/in\/gerrit-gro%C3%9Fmann\/\" class=\"jet-engine-listing-overlay-link\" target=\"_blank\"><\/a><\/div><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1864e33 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"1864e33\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-xl\" href=\"https:\/\/ai-grid.org\/mentors\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Alle Mentor:innen ansehen \u2192<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Mitmachen als Mentor:in Als AI Grid Mentor:in f\u00f6rdern Sie den KI-Nachwuchs und st\u00e4rken den KI-Standort Deutschland. Sie begleiten talentierte Masterstudierende und Doktorand:innen, bleiben nah an aktuellen Entwicklungen der KI-Forschung und vernetzen sich mit f\u00fchrenden Expert:innen aus Wissenschaft und Wirtschaft. Jetzt bewerben KI-Nachwuchs f\u00f6rdern. Sie profitieren von neuesten Erkenntnissen in KI-Spitzenthemen. Mindestanforderungen f\u00fcr Mentor:innen: &#8211; Bedeutende [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"iawp_total_views":844,"footnotes":""},"class_list":["post-1243","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>F\u00fcr Mentoren - AI GRID<\/title>\n<meta name=\"description\" content=\"Join AI GRID as a mentor: support emerging AI researchers, share expertise, gain access to groundbreaking research, and shape Germany\u2019s AI future. Apply now!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ai-grid.org\/en\/for-mentors\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"For mentors\" \/>\n<meta property=\"og:description\" content=\"Join AI GRID as a mentor: support emerging AI researchers, share expertise, gain access to groundbreaking research, and shape Germany\u2019s AI future\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ai-grid.org\/en\/for-mentors\/\" \/>\n<meta property=\"og:site_name\" content=\"AI GRID\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-09T13:00:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ai-grid.org\/wp-content\/uploads\/2025\/07\/IMG-20250522-WA0010-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"2000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"11 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ai-grid.org\\\/for-mentors\\\/\",\"url\":\"https:\\\/\\\/ai-grid.org\\\/for-mentors\\\/\",\"name\":\"F\u00fcr Mentoren - AI GRID\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ai-grid.org\\\/#website\"},\"datePublished\":\"2024-01-29T10:28:43+00:00\",\"dateModified\":\"2026-03-09T13:00:31+00:00\",\"description\":\"Join AI GRID as a mentor: support emerging AI researchers, share expertise, gain access to groundbreaking research, and shape Germany\u2019s AI future. Apply now!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ai-grid.org\\\/for-mentors\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ai-grid.org\\\/for-mentors\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ai-grid.org\\\/for-mentors\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/ai-grid.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"F\u00fcr Mentoren\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ai-grid.org\\\/#website\",\"url\":\"https:\\\/\\\/ai-grid.org\\\/\",\"name\":\"AI GRID\",\"description\":\"Ein Netzwerk hochrangiger KI-Expert:innen\",\"publisher\":{\"@id\":\"https:\\\/\\\/ai-grid.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ai-grid.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ai-grid.org\\\/#organization\",\"name\":\"AI GRID\",\"url\":\"https:\\\/\\\/ai-grid.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/ai-grid.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ai-grid.org\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/220926_AIGrid_Logo_RGB-01-1920w.png\",\"contentUrl\":\"https:\\\/\\\/ai-grid.org\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/220926_AIGrid_Logo_RGB-01-1920w.png\",\"width\":1920,\"height\":1008,\"caption\":\"AI GRID\"},\"image\":{\"@id\":\"https:\\\/\\\/ai-grid.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"F\u00fcr Mentoren - AI GRID","description":"Join AI GRID as a mentor: support emerging AI researchers, share expertise, gain access to groundbreaking research, and shape Germany\u2019s AI future. Apply now!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ai-grid.org\/en\/for-mentors\/","og_locale":"en_GB","og_type":"article","og_title":"For mentors","og_description":"Join AI GRID as a mentor: support emerging AI researchers, share expertise, gain access to groundbreaking research, and shape Germany\u2019s AI future","og_url":"https:\/\/ai-grid.org\/en\/for-mentors\/","og_site_name":"AI GRID","article_modified_time":"2026-03-09T13:00:31+00:00","og_image":[{"width":900,"height":2000,"url":"https:\/\/ai-grid.org\/wp-content\/uploads\/2025\/07\/IMG-20250522-WA0010-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Estimated reading time":"11 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ai-grid.org\/for-mentors\/","url":"https:\/\/ai-grid.org\/for-mentors\/","name":"F\u00fcr Mentoren - AI GRID","isPartOf":{"@id":"https:\/\/ai-grid.org\/#website"},"datePublished":"2024-01-29T10:28:43+00:00","dateModified":"2026-03-09T13:00:31+00:00","description":"Join AI GRID as a mentor: support emerging AI researchers, share expertise, gain access to groundbreaking research, and shape Germany\u2019s AI future. Apply now!","breadcrumb":{"@id":"https:\/\/ai-grid.org\/for-mentors\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ai-grid.org\/for-mentors\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ai-grid.org\/for-mentors\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/ai-grid.org\/"},{"@type":"ListItem","position":2,"name":"F\u00fcr Mentoren"}]},{"@type":"WebSite","@id":"https:\/\/ai-grid.org\/#website","url":"https:\/\/ai-grid.org\/","name":"AI GRID","description":"Ein Netzwerk hochrangiger KI-Expert:innen","publisher":{"@id":"https:\/\/ai-grid.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ai-grid.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/ai-grid.org\/#organization","name":"AI GRID","url":"https:\/\/ai-grid.org\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/ai-grid.org\/#\/schema\/logo\/image\/","url":"https:\/\/ai-grid.org\/wp-content\/uploads\/2024\/01\/220926_AIGrid_Logo_RGB-01-1920w.png","contentUrl":"https:\/\/ai-grid.org\/wp-content\/uploads\/2024\/01\/220926_AIGrid_Logo_RGB-01-1920w.png","width":1920,"height":1008,"caption":"AI GRID"},"image":{"@id":"https:\/\/ai-grid.org\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/ai-grid.org\/en\/wp-json\/wp\/v2\/pages\/1243","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ai-grid.org\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ai-grid.org\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ai-grid.org\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ai-grid.org\/en\/wp-json\/wp\/v2\/comments?post=1243"}],"version-history":[{"count":223,"href":"https:\/\/ai-grid.org\/en\/wp-json\/wp\/v2\/pages\/1243\/revisions"}],"predecessor-version":[{"id":8928,"href":"https:\/\/ai-grid.org\/en\/wp-json\/wp\/v2\/pages\/1243\/revisions\/8928"}],"wp:attachment":[{"href":"https:\/\/ai-grid.org\/en\/wp-json\/wp\/v2\/media?parent=1243"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}